{"id":411,"date":"2018-05-21T09:18:41","date_gmt":"2018-05-21T08:18:41","guid":{"rendered":"http:\/\/lhg-bw.de\/karlsruhe\/?page_id=411"},"modified":"2024-02-21T19:17:47","modified_gmt":"2024-02-21T18:17:47","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><h2>1. Datenschutz auf einen Blick<\/h2>\n<h3>Allgemeine Hinweise<\/h3>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit<br \/>\nIhren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<h3>Datenerfassung auf unserer Website<\/h3>\n<p><strong>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/strong><\/p>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Impressum dieser Website entnehmen.<\/p>\n<p><strong>Wie erfassen wir Ihre Daten?<\/strong><\/p>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n<p><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/p>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website<br \/>\nzu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet<br \/>\nwerden.<\/p>\n<p><strong>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><\/p>\n<p>Sie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<h3>Analyse-Tools und Tools von Drittanbietern<\/h3>\n<p>Beim Besuch unserer Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit Cookies und mit sogenannten Analyseprogrammen. Die Analyse Ihres Surf-Verhaltens erfolgt in der Regel anonym; das Surf-Verhalten kann nicht zu Ihnen zur\u00fcckverfolgt werden. Sie k\u00f6nnen dieser Analyse widersprechen oder sie durch die Nichtbenutzung bestimmter Tools verhindern. Detaillierte Informationen dazu finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n<p>Sie k\u00f6nnen dieser Analyse widersprechen. \u00dcber die Widerspruchsm\u00f6glichkeiten werden wir Sie in dieser Datenschutzerkl\u00e4rung informieren.<\/p>\n<h2>2. Allgemeine Hinweise und Pflichtinformationen<\/h2>\n<h3>Datenschutz<\/h3>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen<br \/>\nDaten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<h3>Hinweis zur verantwortlichen Stelle<\/h3>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>Landesverband Liberaler Hochschulgruppen Baden-W\u00fcrttemberg (LHG BW)<br \/>\nc\/o FDP Baden-W\u00fcrttemberg \u2013 Rosensteinstra\u00dfe 22 \u2013 70191 Stuttgart<br \/>\nE-Mail: landesvorstand(\u00e4t)lhg-bw.de \u2013 (\u00e4t) bitte gegen das @-Zeichen ersetzen<br \/>\nInternet: <a href=\"http:\/\/www.lhg-bw.de\">www.lhg-bw.de<\/a><\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer<br \/>\nausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung<br \/>\njederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die<br \/>\nRechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf<br \/>\nunber\u00fchrt.<\/p>\n<h3>Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/h3>\n<p>Im Falle datenschutzrechtlicher Verst\u00f6\u00dfe steht dem Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Zust\u00e4ndige Aufsichtsbeh\u00f6rde in<br \/>\ndatenschutzrechtlichen Fragen ist der Landesdatenschutzbeauftragte des Bundeslandes, in dem unser Unternehmen seinen Sitz hat. Eine Liste der Datenschutzbeauftragten sowie deren Kontaktdaten k\u00f6nnen folgendem Link entnommen werden: <a href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_linksnode.<br \/>\nhtml<\/a>.<\/p>\n<h3>Recht auf Daten\u00fcbertragbarkeit<\/h3>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen,<br \/>\nerfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<h3>SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert<br \/>\nist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h3>Auskunft, Sperrung, L\u00f6schung<\/h3>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Hierzu sowie zu<br \/>\nweiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n<h2>3. Datenerfassung auf unserer Website<\/h2>\n<h3>Cookies<\/h3>\n<p>Die Internetseiten verwenden teilweise so genannte Cookies.<br \/>\nCookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert.<\/p>\n<p>Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das<br \/>\nSetzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.B. Warenkorbfunktion) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung<br \/>\nvon Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Soweit andere Cookies (z.B. Cookies zur Analyse Ihres Surfverhaltens) gespeichert werden, werden diese in dieser Datenschutzerkl\u00e4rung gesondert behandelt.<\/p>\n<h3>Server-Log-Dateien<\/h3>\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<ul>\n<li>Browsertyp und<br \/>\nBrowserversion<\/li>\n<li>verwendetes Betriebssystem<\/li>\n<li>Referrer URL<\/li>\n<li>Hostname des<br \/>\nzugreifenden Rechners<\/li>\n<li>Uhrzeit der Serveranfrage<\/li>\n<li>IP-Adresse<\/li>\n<\/ul>\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n<p>Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n<h3>Kontaktformular<\/h3>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden<br \/>\nIhre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung der in das Kontaktformular<br \/>\neingegebenen Daten erfolgt somit ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen diese Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h3>Kommentarfunktion auf dieser Website<\/h3>\n<p>F\u00fcr die Kommentarfunktion auf dieser Seite werden neben Ihrem<br \/>\nKommentar auch Angaben zum Zeitpunkt der Erstellung des Kommentars, Ihre E-Mail-Adresse und, wenn Sie nicht anonym posten, der von Ihnen gew\u00e4hlte Nutzername gespeichert.<\/p>\n<p><strong>Speicherung der IP-Adresse<\/strong><\/p>\n<p>Unsere Kommentarfunktion speichert die IPAdressen<br \/>\nder Nutzer, die Kommentare verfassen. Da wir Kommentare auf unserer Seite nicht vor der Freischaltung pr\u00fcfen, ben\u00f6tigen wir diese Daten, um im Falle von Rechtsverletzungen wie Beleidigungen oder Propaganda gegen den Verfasser vorgehen zu k\u00f6nnen.<\/p>\n<p><strong>Abonnieren von Kommentaren<\/strong><\/p>\n<p>Als Nutzer der Seite k\u00f6nnen Sie nach einer Anmeldung Kommentare abonnieren. Sie erhalten eine Best\u00e4tigungsemail, um zu pr\u00fcfen, ob Sie der Inhaber der angegebenen E-Mail-Adresse sind. Sie k\u00f6nnen diese Funktion jederzeit \u00fcber einen Link in den Info-Mails abbestellen. Die im Rahmen des Abonnierens von Kommentaren eingegebenen Daten werden in diesem Fall gel\u00f6scht; wenn Sie diese Daten f\u00fcr andere Zwecke und an anderer Stelle (z.B. Newsletterbestellung) an uns \u00fcbermittelt haben, verbleiben die jedoch bei uns.<\/p>\n<p><strong>Speicherdauer der Kommentare<\/strong><\/p>\n<p>Die Kommentare und die damit verbundenen Daten (z.B. IP-Adresse) werden gespeichert und verbleiben auf unserer Website, bis der kommentierte Inhalt vollst\u00e4ndig gel\u00f6scht wurde oder die Kommentare aus rechtlichen Gr\u00fcnden gel\u00f6scht werden m\u00fcssen (z.B. beleidigende Kommentare).<\/p>\n<p><strong>Rechtsgrundlage<\/strong><\/p>\n<p>Die Speicherung der Kommentare erfolgt auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen eine von Ihnen erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<h2>4. Analyse Tools und Werbung<\/h2>\n<h3>WordPress Stats<\/h3>\n<p>Diese Website nutzt das WordPress Tool Stats, um Besucherzugriffe statistisch auszuwerten. Anbieter ist die Automattic Inc., 60 29th Street #343, San Francisco, CA 94110-4929, USA.<\/p>\n<p>WordPress Stats verwendet Cookies, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website erlauben. Die durch die Cookies generierten Informationen \u00fcber die Benutzung unserer Website werden auf Servern in den USA gespeichert. Ihre IP-Adresse wird nach der Verarbeitung und vor der Speicherung anonymisiert.<\/p>\n<p>\u201cWordPress-Stats\u201d-Cookies verbleiben auf Ihrem Endger\u00e4t, bis Sie sie l\u00f6schen.<\/p>\n<p>Die Speicherung von \u201cWordPress Stats\u201d-Cookies erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes<br \/>\nInteresse an der anonymisierten Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von<br \/>\nCookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische<br \/>\nL\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.<\/p>\n<p>Sie k\u00f6nnen der Erhebung und Nutzung Ihrer Daten f\u00fcr die Zukunft widersprechen, indem Sie mit einem Klick auf diesen Link einen Opt-Out-Cookie in Ihrem Browser setzen: <a href=\"https:\/\/www.quantcast.com\/opt-out\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.quantcast.com\/opt-out\/<\/a>.<\/p>\n<p>Wenn Sie die Cookies auf Ihrem Rechner l\u00f6schen, m\u00fcssen Sie den Opt-Out-Cookie erneut setzen.<\/p>\n<h3>Google reCAPTCHA<\/h3>\n<p>Wir nutzen \u201cGoogle reCAPTCHA\u201d (im Folgenden \u201creCAPTCHA\u201d) auf unseren Websites. Anbieter ist die Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (\u201cGoogle\u201d).<\/p>\n<p>Mit reCAPTCHA soll \u00fcberpr\u00fcft werden, ob die Dateneingabe auf unseren Websites (z.B. in einem Kontaktformular) durch einen Menschen oder durch ein automatisiertes Programm erfolgt. Hierzu analysiert reCAPTCHA das Verhalten des Websitebesuchers anhand verschiedener Merkmale. Diese Analyse beginnt automatisch, sobald der Websitebesucher die Website betritt. Zur Analyse wertet reCAPTCHA verschiedene Informationen aus (z.B. IP-Adresse, Verweildauer des Websitebesuchers auf<br \/>\nder Website oder vom Nutzer get\u00e4tigte Mausbewegungen). Die bei der Analyse erfassten Daten werden an Google weitergeleitet.<\/p>\n<p>Die reCAPTCHA-Analysen laufen vollst\u00e4ndig im<br \/>\nHintergrund. Websitebesucher werden nicht darauf hingewiesen, dass eine Analyse stattfindet.<\/p>\n<p>Die Datenverarbeitung erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse daran, seine Webangebote vor missbr\u00e4uchlicher automatisierter Aussp\u00e4hung und vor SPAM zu sch\u00fctzen.<\/p>\n<p>Weitere Informationen zu Google reCAPTCHA sowie die Datenschutzerkl\u00e4rung von Google entnehmen Sie folgenden Links: <a href=\"https:\/\/www.google.com\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/intl\/de\/policies\/privacy\/<\/a> und <a href=\"https:\/\/www.google.com\/recaptcha\/intro\/android.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/recaptcha\/intro\/android.html<\/a>.<\/p>\n<h2>5. Plugins und Tools<\/h2>\n<h3>YouTube<\/h3>\n<p>Unsere Website nutzt Plugins der von Google betriebenen Seite<br \/>\nYouTube. Betreiber der Seiten ist die YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem YouTube-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben.<\/p>\n<p>Wenn Sie in Ihrem YouTube-Account eingeloggt sind,<br \/>\nerm\u00f6glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p>\n<p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote.<br \/>\nDies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von YouTube<br \/>\nunter: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy<\/a>.<\/p>\n<h3>Google Maps<\/h3>\n<p>Diese Seite nutzt \u00fcber eine API den Kartendienst Google Maps. Anbieter ist die Google Inc.,<br \/>\n1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/p>\n<p>Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP Adresse zu speichern. Diese Informationen werden in der Regel an<br \/>\neinen Server von Google in den USA \u00fcbertragen und dort gespeichert. Der Anbieter dieser Seite hat<br \/>\nkeinen Einfluss auf diese Daten\u00fcbertragung.<\/p>\n<p>Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit<br \/>\nder von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6<br \/>\nAbs. 1 lit. f DSGVO dar.<\/p>\n<p>Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der<br \/>\nDatenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>.<\/p>\n<h3>Facebook<\/h3>\n<p>Auf diesen Internetseiten werden Plugins des sozialen Netzwerkes facebook.com verwendet, das von der Facebook Inc., 1601 S. California Ave, Palo Alto, CA 94304, USA betrieben wird (\u201cFacebook\u201d).<br \/>\nWenn Sie mit einen solchen Plugin versehene Internetseiten unserer Internetpr\u00e4senz aufrufen, wird eine Verbindung zu den Facebook-Servern hergestellt und dabei das Plugin durch Mitteilung an Ihren Browser auf der Internetseite dargestellt. Hierdurch wird an den Facebook-Server \u00fcbermittelt, welche unserer Internetseiten Sie besucht haben. Sind Sie dabei als Mitglied bei Facebook eingeloggt, ordnet Facebook diese Information Ihrem pers\u00f6nlichen Facebook-Benutzerkonto zu. Bei der Nutzung der Plugin-Funktionen (z.B. Anklicken des \u201eGef\u00e4llt mir\u201c-Buttons, Abgabe eines Kommentars) werden auch diese Informationen Ihrem Facebook-Konto zugeordnet, was Sie nur durch Ausloggen vor Nutzung des Plugins verhindern k\u00f6nnen.<br \/>\nN\u00e4here Informationen zur Erhebung und Nutzung der Daten durch Facebook, \u00fcber Ihre diesbez\u00fcglichen Rechte M\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re finden Sie in den Datenschutzhinweisen von Facebook.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Website [&hellip;]<\/p>\n","protected":false},"author":1065,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-411","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzerkl\u00e4rung - LHG Karlsruhe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - LHG Karlsruhe\" \/>\n<meta property=\"og:description\" content=\"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Website [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"LHG Karlsruhe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T18:17:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lhg-bw.de\/karlsruhe\/files\/2024\/04\/1712077509853891676212056.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/\",\"url\":\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/\",\"name\":\"Datenschutzerkl\u00e4rung - LHG Karlsruhe\",\"isPartOf\":{\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#website\"},\"datePublished\":\"2018-05-21T08:18:41+00:00\",\"dateModified\":\"2024-02-21T18:17:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/lhg-bw.de\/karlsruhe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#website\",\"url\":\"https:\/\/lhg-bw.de\/karlsruhe\/\",\"name\":\"Liberale Hochschulgruppe Karlsruhe\",\"description\":\"Wilkommen bei der LHG Karlsruhe!\",\"publisher\":{\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#organization\"},\"alternateName\":\"LHG Karlsruhe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lhg-bw.de\/karlsruhe\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#organization\",\"name\":\"Liberale Hochschulgruppe Karlsruhe\",\"alternateName\":\"LHG Karlsruhe\",\"url\":\"https:\/\/lhg-bw.de\/karlsruhe\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lhg-bw.de\/karlsruhe\/files\/2025\/06\/LHG-Logo-Website.png\",\"contentUrl\":\"https:\/\/lhg-bw.de\/karlsruhe\/files\/2025\/06\/LHG-Logo-Website.png\",\"width\":2200,\"height\":600,\"caption\":\"Liberale Hochschulgruppe Karlsruhe\"},\"image\":{\"@id\":\"https:\/\/lhg-bw.de\/karlsruhe\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lhg_karlsruhe\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - LHG Karlsruhe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - LHG Karlsruhe","og_description":"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Website [&hellip;]","og_url":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/","og_site_name":"LHG Karlsruhe","article_modified_time":"2024-02-21T18:17:47+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/lhg-bw.de\/karlsruhe\/files\/2024\/04\/1712077509853891676212056.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/","url":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - LHG Karlsruhe","isPartOf":{"@id":"https:\/\/lhg-bw.de\/karlsruhe\/#website"},"datePublished":"2018-05-21T08:18:41+00:00","dateModified":"2024-02-21T18:17:47+00:00","breadcrumb":{"@id":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lhg-bw.de\/karlsruhe\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lhg-bw.de\/karlsruhe\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/lhg-bw.de\/karlsruhe\/#website","url":"https:\/\/lhg-bw.de\/karlsruhe\/","name":"Liberale Hochschulgruppe Karlsruhe","description":"Wilkommen bei der LHG Karlsruhe!","publisher":{"@id":"https:\/\/lhg-bw.de\/karlsruhe\/#organization"},"alternateName":"LHG Karlsruhe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lhg-bw.de\/karlsruhe\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/lhg-bw.de\/karlsruhe\/#organization","name":"Liberale Hochschulgruppe Karlsruhe","alternateName":"LHG Karlsruhe","url":"https:\/\/lhg-bw.de\/karlsruhe\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lhg-bw.de\/karlsruhe\/#\/schema\/logo\/image\/","url":"https:\/\/lhg-bw.de\/karlsruhe\/files\/2025\/06\/LHG-Logo-Website.png","contentUrl":"https:\/\/lhg-bw.de\/karlsruhe\/files\/2025\/06\/LHG-Logo-Website.png","width":2200,"height":600,"caption":"Liberale Hochschulgruppe Karlsruhe"},"image":{"@id":"https:\/\/lhg-bw.de\/karlsruhe\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lhg_karlsruhe\/"]}]}},"_links":{"self":[{"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/pages\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/users\/1065"}],"replies":[{"embeddable":true,"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":5,"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/pages\/411\/revisions"}],"predecessor-version":[{"id":780,"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/pages\/411\/revisions\/780"}],"wp:attachment":[{"href":"https:\/\/lhg-bw.de\/karlsruhe\/wp-json\/wp\/v2\/media?parent=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}